{"id":1851,"count":1,"description":"","link":"https:\/\/legaltree.nl\/en\/tag\/harvo-en\/","name":"HARVO","slug":"harvo-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HARVO Archieven - Legaltree Advocaten en Notarissen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/legaltree.nl\/en\/tag\/harvo-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HARVO Archieven - Legaltree Advocaten en Notarissen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/legaltree.nl\/en\/tag\/harvo-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Legaltree Advocaten en Notarissen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/legaltree.nl\\\/en\\\/tag\\\/harvo-en\\\/\",\"url\":\"https:\\\/\\\/legaltree.nl\\\/en\\\/tag\\\/harvo-en\\\/\",\"name\":\"HARVO Archieven - Legaltree Advocaten en Notarissen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/legaltree.nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/legaltree.nl\\\/en\\\/tag\\\/harvo-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/legaltree.nl\\\/en\\\/tag\\\/harvo-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/legaltree.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HARVO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/legaltree.nl\\\/#website\",\"url\":\"https:\\\/\\\/legaltree.nl\\\/\",\"name\":\"Legaltree Advocaten en Notarissen\",\"description\":\"Quality is personal\",\"publisher\":{\"@id\":\"https:\\\/\\\/legaltree.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/legaltree.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/legaltree.nl\\\/#organization\",\"name\":\"Legaltree Advocaten\",\"url\":\"https:\\\/\\\/legaltree.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/legaltree.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/legaltree.nl\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/legaltree.nl\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/favicon.png\",\"width\":180,\"height\":180,\"caption\":\"Legaltree Advocaten\"},\"image\":{\"@id\":\"https:\\\/\\\/legaltree.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HARVO Archieven - Legaltree Advocaten en Notarissen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/legaltree.nl\/en\/tag\/harvo-en\/","og_locale":"en_US","og_type":"article","og_title":"HARVO Archieven - Legaltree Advocaten en Notarissen","og_url":"https:\/\/legaltree.nl\/en\/tag\/harvo-en\/","og_site_name":"Legaltree Advocaten en Notarissen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/legaltree.nl\/en\/tag\/harvo-en\/","url":"https:\/\/legaltree.nl\/en\/tag\/harvo-en\/","name":"HARVO Archieven - Legaltree Advocaten en Notarissen","isPartOf":{"@id":"https:\/\/legaltree.nl\/#website"},"breadcrumb":{"@id":"https:\/\/legaltree.nl\/en\/tag\/harvo-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/legaltree.nl\/en\/tag\/harvo-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/legaltree.nl\/"},{"@type":"ListItem","position":2,"name":"HARVO"}]},{"@type":"WebSite","@id":"https:\/\/legaltree.nl\/#website","url":"https:\/\/legaltree.nl\/","name":"Legaltree Advocaten en Notarissen","description":"Quality is personal","publisher":{"@id":"https:\/\/legaltree.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/legaltree.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/legaltree.nl\/#organization","name":"Legaltree Advocaten","url":"https:\/\/legaltree.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/legaltree.nl\/#\/schema\/logo\/image\/","url":"https:\/\/legaltree.nl\/wp-content\/uploads\/2018\/11\/favicon.png","contentUrl":"https:\/\/legaltree.nl\/wp-content\/uploads\/2018\/11\/favicon.png","width":180,"height":180,"caption":"Legaltree Advocaten"},"image":{"@id":"https:\/\/legaltree.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/legaltree.nl\/en\/wp-json\/wp\/v2\/tags\/1851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legaltree.nl\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/legaltree.nl\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/legaltree.nl\/en\/wp-json\/wp\/v2\/posts?tags=1851"},{"href":"https:\/\/legaltree.nl\/en\/wp-json\/wp\/v2\/profiel?tags=1851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}